{"id":6724,"date":"2016-01-18T19:20:47","date_gmt":"2016-01-18T18:20:47","guid":{"rendered":"http:\/\/www.deltaturistic.com\/?post_type=product&#038;p=6724"},"modified":"2019-09-06T23:47:21","modified_gmt":"2019-09-06T22:47:21","slug":"sabo-de-mans-mel","status":"publish","type":"product","link":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/","title":{"rendered":"sab\u00f3 de mans mel"},"content":{"rendered":"<p>sab\u00f3 de mans artes\u00e0, 100% oli de coco\u00a0natural. \u00a0 4.5 gr<\/p>\n<p>&nbsp;<\/p>\n<p>MEL : regenerant i nutritiu, per a pells sensibles, normals i seques<\/p>\n","protected":false},"excerpt":{"rendered":"<p>sab\u00f3 de mans perfumat<\/p>\n","protected":false},"featured_media":6518,"template":"","meta":[],"product_brand":[],"product_cat":[646],"product_tag":[],"class_list":["post-6724","product","type-product","status-publish","has-post-thumbnail","product_cat-cosmetica-natural-ecologica","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sab\u00f3 de mans mel - Turismo, excursiones y deportes de aventura en ell delta del Ebro<\/title>\n<meta name=\"description\" content=\"sab\u00f3 de mans artes\u00e0 natural 100% oli de coco. El de mel t\u00e9 propietats regenerants\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/\",\"url\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/\",\"name\":\"sab\u00f3 de mans mel - Turismo, excursiones y deportes de aventura en ell delta del Ebro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deltaturistic.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/CAM002731.jpg\",\"datePublished\":\"2016-01-18T18:20:47+00:00\",\"dateModified\":\"2019-09-06T22:47:21+00:00\",\"description\":\"sab\u00f3 de mans artes\u00e0 natural 100% oli de coco. El de mel t\u00e9 propietats regenerants\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deltaturistic.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/CAM002731.jpg\",\"contentUrl\":\"https:\\\/\\\/deltaturistic.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/CAM002731.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/paquets-turistics\\\/sabo-de-mans-mel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes tur\u00edstics\",\"item\":\"https:\\\/\\\/deltaturistic.com\\\/paquets-turistics\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sab\u00f3 de mans mel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/\",\"name\":\"Turismo, excursiones y deportes de aventura en ell delta del Ebro\",\"description\":\"Turismo, excursiones y deportes de aventura en el delta del Ebro. Agencia de Viages Deltaturistic\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deltaturistic.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sab\u00f3 de mans mel - Turismo, excursiones y deportes de aventura en ell delta del Ebro","description":"sab\u00f3 de mans artes\u00e0 natural 100% oli de coco. El de mel t\u00e9 propietats regenerants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/","url":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/","name":"sab\u00f3 de mans mel - Turismo, excursiones y deportes de aventura en ell delta del Ebro","isPartOf":{"@id":"https:\/\/deltaturistic.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/#primaryimage"},"image":{"@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/#primaryimage"},"thumbnailUrl":"https:\/\/deltaturistic.com\/wp-content\/uploads\/2015\/12\/CAM002731.jpg","datePublished":"2016-01-18T18:20:47+00:00","dateModified":"2019-09-06T22:47:21+00:00","description":"sab\u00f3 de mans artes\u00e0 natural 100% oli de coco. El de mel t\u00e9 propietats regenerants","breadcrumb":{"@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/#primaryimage","url":"https:\/\/deltaturistic.com\/wp-content\/uploads\/2015\/12\/CAM002731.jpg","contentUrl":"https:\/\/deltaturistic.com\/wp-content\/uploads\/2015\/12\/CAM002731.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/deltaturistic.com\/es\/paquets-turistics\/sabo-de-mans-mel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/deltaturistic.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productes tur\u00edstics","item":"https:\/\/deltaturistic.com\/paquets-turistics\/"},{"@type":"ListItem","position":3,"name":"sab\u00f3 de mans mel"}]},{"@type":"WebSite","@id":"https:\/\/deltaturistic.com\/es\/#website","url":"https:\/\/deltaturistic.com\/es\/","name":"Turismo, excursiones y deportes de aventura en ell delta del Ebro","description":"Turismo, excursiones y deportes de aventura en el delta del Ebro. Agencia de Viages Deltaturistic","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deltaturistic.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/product\/6724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/media\/6518"}],"wp:attachment":[{"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/media?parent=6724"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/product_brand?post=6724"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/product_cat?post=6724"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deltaturistic.com\/es\/wp-json\/wp\/v2\/product_tag?post=6724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}